{"id":602,"count":2,"description":"","link":"http:\/\/www.thainame.net\/edu\/tag\/nurse\/","name":"nurse","slug":"nurse","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>nurse Archives - \u0e2d\u0e35\u0e14\u0e39\u0e19\u0e34\u0e27\u0e2a\u0e4c<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.thainame.net\/edu\/tag\/nurse\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"nurse Archives - \u0e2d\u0e35\u0e14\u0e39\u0e19\u0e34\u0e27\u0e2a\u0e4c\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.thainame.net\/edu\/tag\/nurse\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e2d\u0e35\u0e14\u0e39\u0e19\u0e34\u0e27\u0e2a\u0e4c\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@thaiabc\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"http:\/\/www.thainame.net\/edu\/tag\/nurse\/\",\"url\":\"http:\/\/www.thainame.net\/edu\/tag\/nurse\/\",\"name\":\"nurse Archives - \u0e2d\u0e35\u0e14\u0e39\u0e19\u0e34\u0e27\u0e2a\u0e4c\",\"isPartOf\":{\"@id\":\"http:\/\/www.thainame.net\/edu\/#website\"},\"breadcrumb\":{\"@id\":\"http:\/\/www.thainame.net\/edu\/tag\/nurse\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/www.thainame.net\/edu\/tag\/nurse\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/www.thainame.net\/edu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"nurse\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/www.thainame.net\/edu\/#website\",\"url\":\"http:\/\/www.thainame.net\/edu\/\",\"name\":\"\u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\",\"description\":\"\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e07\u0e04\u0e21\",\"publisher\":{\"@id\":\"http:\/\/www.thainame.net\/edu\/#organization\"},\"alternateName\":\"Education news in Thailand\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/www.thainame.net\/edu\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\/\/www.thainame.net\/edu\/#organization\",\"name\":\"\u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\",\"url\":\"http:\/\/www.thainame.net\/edu\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\/\/www.thainame.net\/edu\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/www.thainame.net\/edu\/wp-content\/uploads\/2023\/09\/cropped-me180.jpg\",\"contentUrl\":\"http:\/\/www.thainame.net\/edu\/wp-content\/uploads\/2023\/09\/cropped-me180.jpg\",\"width\":180,\"height\":60,\"caption\":\"\u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\"},\"image\":{\"@id\":\"http:\/\/www.thainame.net\/edu\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/web.facebook.com\/thaiall\",\"https:\/\/x.com\/thaiabc\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"nurse Archives - \u0e2d\u0e35\u0e14\u0e39\u0e19\u0e34\u0e27\u0e2a\u0e4c","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.thainame.net\/edu\/tag\/nurse\/","og_locale":"en_US","og_type":"article","og_title":"nurse Archives - \u0e2d\u0e35\u0e14\u0e39\u0e19\u0e34\u0e27\u0e2a\u0e4c","og_url":"http:\/\/www.thainame.net\/edu\/tag\/nurse\/","og_site_name":"\u0e2d\u0e35\u0e14\u0e39\u0e19\u0e34\u0e27\u0e2a\u0e4c","twitter_card":"summary_large_image","twitter_site":"@thaiabc","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"http:\/\/www.thainame.net\/edu\/tag\/nurse\/","url":"http:\/\/www.thainame.net\/edu\/tag\/nurse\/","name":"nurse Archives - \u0e2d\u0e35\u0e14\u0e39\u0e19\u0e34\u0e27\u0e2a\u0e4c","isPartOf":{"@id":"http:\/\/www.thainame.net\/edu\/#website"},"breadcrumb":{"@id":"http:\/\/www.thainame.net\/edu\/tag\/nurse\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"http:\/\/www.thainame.net\/edu\/tag\/nurse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/www.thainame.net\/edu\/"},{"@type":"ListItem","position":2,"name":"nurse"}]},{"@type":"WebSite","@id":"http:\/\/www.thainame.net\/edu\/#website","url":"http:\/\/www.thainame.net\/edu\/","name":"\u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32","description":"\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e07\u0e04\u0e21","publisher":{"@id":"http:\/\/www.thainame.net\/edu\/#organization"},"alternateName":"Education news in Thailand","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.thainame.net\/edu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/www.thainame.net\/edu\/#organization","name":"\u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32","url":"http:\/\/www.thainame.net\/edu\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/www.thainame.net\/edu\/#\/schema\/logo\/image\/","url":"http:\/\/www.thainame.net\/edu\/wp-content\/uploads\/2023\/09\/cropped-me180.jpg","contentUrl":"http:\/\/www.thainame.net\/edu\/wp-content\/uploads\/2023\/09\/cropped-me180.jpg","width":180,"height":60,"caption":"\u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32"},"image":{"@id":"http:\/\/www.thainame.net\/edu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/thaiall","https:\/\/x.com\/thaiabc"]}]}},"_links":{"self":[{"href":"http:\/\/www.thainame.net\/edu\/wp-json\/wp\/v2\/tags\/602","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.thainame.net\/edu\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/www.thainame.net\/edu\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/www.thainame.net\/edu\/wp-json\/wp\/v2\/posts?tags=602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}